{"id":357,"date":"2025-09-18T11:11:44","date_gmt":"2025-09-18T11:11:44","guid":{"rendered":"https:\/\/literatabeergarden.com\/?page_id=357"},"modified":"2025-10-21T09:49:25","modified_gmt":"2025-10-21T09:49:25","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/literatabeergarden.com\/en\/aviso-legal\/","title":{"rendered":"Legal Notice"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"357\" class=\"elementor elementor-357\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bc67c8 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9bc67c8\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-86f4de2\" data-id=\"86f4de2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b4d38c elementor-widget elementor-widget-image\" data-id=\"7b4d38c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"288\" src=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png\" class=\"attachment-full size-full wp-image-106\" alt=\"\" srcset=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png 800w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco-300x108.png 300w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco-768x276.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-65ffc53\" data-id=\"65ffc53\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f466cc elementor-widget elementor-widget-jkit_nav_menu\" data-id=\"7f466cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"jkit_nav_menu.default\">\n\t\t\t\t\t<div  class=\"jeg-elementor-kit jkit-nav-menu break-point-tablet submenu-click-title jeg_module___6a987d638527e\"  data-item-indicator=\"&lt;i aria-hidden=&quot;true&quot; class=&quot;jki jki-chevron-down-light&quot;&gt;&lt;\/i&gt;\"><button aria-label=\"open-menu\" class=\"jkit-hamburger-menu\"><i aria-hidden=\"true\" class=\"jki jki-bars-solid\"><\/i><\/button>\n        <div class=\"jkit-menu-wrapper\"><div class=\"jkit-menu-container\"><ul id=\"menu-literata-menu\" class=\"jkit-menu jkit-menu-direction-flex jkit-submenu-position-top\"><li id=\"menu-item-99\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-99\"><a href=\"https:\/\/literatabeergarden.com\/en\/\">Home<\/a><\/li>\n<li id=\"menu-item-273\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-273\"><a href=\"https:\/\/literatabeergarden.com\/en\/nosotros\/\">About Us<\/a><\/li>\n<li id=\"menu-item-329\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-329\"><a href=\"https:\/\/literatabeergarden.com\/en\/menu\/\">Menu<\/a><\/li>\n<li id=\"menu-item-328\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-328\"><a href=\"https:\/\/literatabeergarden.com\/en\/contacto\/\">Contact<\/a><\/li>\n<\/ul><\/div>\n            <div class=\"jkit-nav-identity-panel\">\n                <div class=\"jkit-nav-site-title\"><a href=\"https:\/\/literatabeergarden.com\/en\" class=\"jkit-nav-logo\" aria-label=\"Home Link\"><img decoding=\"async\" width=\"800\" height=\"288\" src=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-color.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-color.png 800w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-color-300x108.png 300w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-color-768x276.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/div>\n                <button aria-label=\"close-menu\" class=\"jkit-close-menu\"><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-times\" viewbox=\"0 0 352 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M242.72 256l100.07-100.07c12.28-12.28 12.28-32.19 0-44.48l-22.24-22.24c-12.28-12.28-32.19-12.28-44.48 0L176 189.28 75.93 89.21c-12.28-12.28-32.19-12.28-44.48 0L9.21 111.45c-12.28 12.28-12.28 32.19 0 44.48L109.28 256 9.21 356.07c-12.28 12.28-12.28 32.19 0 44.48l22.24 22.24c12.28 12.28 32.2 12.28 44.48 0L176 322.72l100.07 100.07c12.28 12.28 32.2 12.28 44.48 0l22.24-22.24c12.28-12.28 12.28-32.19 0-44.48L242.72 256z\"><\/path><\/svg><\/button>\n            <\/div>\n        <\/div>\n        <div class=\"jkit-overlay\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3095c65 elementor-hidden-phone elementor-hidden-tablet\" data-id=\"3095c65\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-942855b elementor-align-right elementor-widget elementor-widget-button\" data-id=\"942855b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/glovoapp.com\/es\/es\/bayona\/literata-bayona\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-concierge-bell\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M288 130.54V112h16c8.84 0 16-7.16 16-16V80c0-8.84-7.16-16-16-16h-96c-8.84 0-16 7.16-16 16v16c0 8.84 7.16 16 16 16h16v18.54C115.49 146.11 32 239.18 32 352h448c0-112.82-83.49-205.89-192-221.46zM496 384H16c-8.84 0-16 7.16-16 16v32c0 8.84 7.16 16 16 16h480c8.84 0 16-7.16 16-16v-32c0-8.84-7.16-16-16-16z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Home delivery<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5867230d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5867230d\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-432c1e9b\" data-id=\"432c1e9b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-820de94 elementor-widget elementor-widget-heading\" data-id=\"820de94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Legal Notice<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-79f58b54 elementor-icon-list--layout-inline elementor-align-center elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"79f58b54\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items elementor-inline-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item elementor-inline-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-right\" viewbox=\"0 0 320 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M285.476 272.971L91.132 467.314c-9.373 9.373-24.569 9.373-33.941 0l-22.667-22.667c-9.357-9.357-9.375-24.522-.04-33.901L188.505 256 34.484 101.255c-9.335-9.379-9.317-24.544.04-33.901l22.667-22.667c9.373-9.373 24.569-9.373 33.941 0L285.475 239.03c9.373 9.372 9.373 24.568.001 33.941z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Aviso legal<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6bfd4082 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6bfd4082\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-22350002\" data-id=\"22350002\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cda4c2b elementor-widget elementor-widget-text-editor\" data-id=\"2cda4c2b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div class=\"row\"><div class=\"col col-xl-10 mx-auto\"><div class=\"paper\"><header class=\"text-center\"><h2 class=\"m-auto\">AVISO LEGAL Y CONDICIONES GENERALES DE USO<\/h2><h4><span class=\"blanc-space ng-binding\">https:\/\/www.literatabeergarden.com<\/span><\/h4><\/header><div><h3>I. INFORMACI\u00d3N GENERAL<\/h3><p>En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web:<\/p><p class=\"ng-hide\">La titularidad de este sitio web, <span class=\"blanc-space ng-binding\">https:\/\/www.literatabeergarden.com<\/span>, (en adelante, Sitio Web) la ostenta: <span class=\"blanc-space ng-binding\">Carolina Salgueiro Quintas<\/span>, con NIF: <span class=\"blanc-space ng-binding\">53171368Z<\/span>, y cuyos datos de contacto son:<\/p><p>Direcci\u00f3n: <span class=\"blanc-space ng-binding\">Estrada pola via 122 Local 3, 36350, Nigr\u00e1n, Pontevedra<\/span><\/p><p>Tel\u00e9fono de contacto: <span class=\"blanc-space ng-binding\">617419726<\/span><\/p><p>Email de contacto: <span class=\"blanc-space ng-binding\">info@literatabeergarden.com<\/span><\/p><h3>II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO<\/h3><h4>El objeto de las condiciones: El Sitio Web<\/h4><p>El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios).<\/p><p><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p><p>El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario.<\/p><p class=\"ng-hide\">Aparte del coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso, y que hubiere contratado el Usuario, algunos de los Contenidos o Servicios ofrecidos por <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> o, en su caso, terceros a trav\u00e9s del Sitio Web pueden encontrarse sujetos a la contrataci\u00f3n previa del Contenido o Servicio, en cuyo caso se especificar\u00e1 de forma clara y\/o se pondr\u00e1 a disposici\u00f3n del Usuario las correspondientes Condiciones Generales o Particulares por las que esto se rija.<\/p><p class=\"ng-hide\">La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario.<\/p><p class=\"\">La utilizaci\u00f3n de los Contenidos no requiere previa suscripci\u00f3n o registro alguno.<\/p><h4>El Usuario<\/h4><p>El acceso, la navegaci\u00f3n y uso del Sitio Web, <span class=\"ng-hide\">as\u00ed como por los espacios habilitados para interactuar entre los Usuarios, y el Usuario y <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span>, como los comentarios y\/o espacios de blogging,<\/span> confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web.<\/p><p>El Sitio Web de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a:<\/p><ul><li>Un uso de la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> sin que sea contrario a lo dispuesto por las presentes Condiciones, la Ley, la moral o el orden p\u00fablico, o que de cualquier otro modo puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del Sitio Web.<\/li><li>La veracidad y licitud de las informaciones aportadas por el Usuario en los formularios extendidos por <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> para el acceso a ciertos Contenidos o Servicios ofrecidos por el Sitio Web. En todo caso, el Usuario notificar\u00e1 de forma inmediata a <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> acerca de cualquier hecho que permita el uso indebido de la informaci\u00f3n registrada en dichos formularios, tales como, pero no solo, el robo, extrav\u00edo, o el acceso no autorizado a identificadores y\/o contrase\u00f1as, con el fin de proceder a su inmediata cancelaci\u00f3n.<\/li><\/ul><p class=\"ng-hide\"><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> se reserva el derecho de retirar todos aquellos comentarios y aportaciones que vulneren la ley, el respeto a la dignidad de la persona, que sean discriminatorios, xen\u00f3fobos, racistas, pornogr\u00e1ficos, spamming, que atenten contra la juventud o la infancia, el orden o la seguridad p\u00fablica o que, a su juicio, no resultaran adecuados para su publicaci\u00f3n.<\/p><p class=\"ng-hide\">En cualquier caso, <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no ser\u00e1 responsable de las opiniones vertidas por los Usuarios a trav\u00e9s de comentarios u otras herramientas de blogging o de participaci\u00f3n que pueda haber.<\/p><p>El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> y el Usuario.<\/p><p class=\"ng-hide\">El Usuario declara ser mayor de edad y disponer de la capacidad jur\u00eddica suficiente para vincularse por las presentes Condiciones. Por lo tanto, este Sitio Web de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no se dirige a menores de edad. <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> declina cualquier responsabilidad por el incumplimiento de este requisito.<\/p><p class=\"\">Siempre en el respeto de la legislaci\u00f3n vigente, este Sitio Web de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> se dirige a todas las personas, sin importar su edad, que puedan acceder y\/o navegar por las p\u00e1ginas del Sitio Web.<\/p><p class=\"ng-hide\">El Sitio Web est\u00e1 dirigido principalmente a Usuarios residentes en . <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no asegura que el Sitio Web cumpla con legislaciones de otros pa\u00edses, ya sea total o parcialmente. Si el Usuario reside o tiene su domiciliado en otro lugar y decide acceder y\/o navegar en el Sitio Web lo har\u00e1 bajo su propia responsabilidad, deber\u00e1 asegurarse de que tal acceso y navegaci\u00f3n cumple con la legislaci\u00f3n local que le es aplicable, no asumiendo <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> responsabilidad alguna que se pueda derivar de dicho acceso.<\/p><h3>III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB: EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/h3><p><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios. <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error.<\/p><p>Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus.<\/p><p><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir.<\/p><h3>IV. POL\u00cdTICA DE ENLACES<\/h3><p class=\"ng-hide\">Se informa que el Sitio Web de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros.<\/p><p class=\"ng-hide\">La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos.<\/p><p class=\"ng-hide\"><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados.<\/p><p class=\"ng-hide\"><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> ofrece contenidos patrocinados, anuncios y\/o enlaces de afiliados. La informaci\u00f3n que aparece en estos enlaces de afiliados o los anuncios insertados, son facilitados por los propios anunciantes, por lo que <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no se hace responsable de posibles inexactitudes o errores que pudieran contener los anuncios, ni garantiza en modo alguno la experiencia, integridad o responsabilidad de los anunciantes o la calidad de sus productos y\/o servicios.<\/p><p class=\"ng-hide\">Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces.<\/p><p class=\"ng-hide\"><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados.<\/p><p class=\"ng-hide\"><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> y que sean enlazados en este Sitio Web.<\/p><p>El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> deber\u00e1 saber que:<\/p><p>No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span>.<\/p><p>No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre el Sitio Web de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span>, ni sobre los Contenidos y\/o Servicios del mismo.<\/p><p>A excepci\u00f3n del hiperv\u00ednculo, el sitio web en el que se establezca dicho hiperenlace no contendr\u00e1 ning\u00fan elemento, de este Sitio Web, protegido como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, salvo autorizaci\u00f3n expresa de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span>.<\/p><p>El establecimiento del hiperv\u00ednculo no implicar\u00e1 la existencia de relaciones entre <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> y el titular del sitio web desde el cual se realice, ni el conocimiento y aceptaci\u00f3n de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> de los contenidos, servicios y\/o actividades ofrecidas en dicho sitio web, y viceversa.<\/p><h3>V. PROPIEDAD INTELECTUAL E INDUSTRIAL<\/h3><p><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> por s\u00ed o como parte cesionaria, es titular de todos los derechos de propiedad intelectual e industrial del Sitio Web, as\u00ed como de los elementos contenidos en el mismo (a t\u00edtulo enunciativo y no exhaustivo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.). Ser\u00e1n, por consiguiente, obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, si\u00e9ndoles aplicables tanto la normativa espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a.<\/p><p>Todos los derechos reservados. En virtud de lo dispuesto en la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span>.<\/p><p>El Usuario se compromete a respetar los derechos de propiedad intelectual e industrial de <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span>. Podr\u00e1 visualizar los elementos del Sitio Web o incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, exclusivamente, para su uso personal. El Usuario, sin embargo, no podr\u00e1 suprimir, alterar, o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en el Sitio Web.<\/p><p>En caso de que el Usuario o tercero considere que cualquiera de los Contenidos del Sitio Web suponga una violaci\u00f3n de los derechos de protecci\u00f3n de la propiedad intelectual, deber\u00e1 comunicarlo inmediatamente a <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> a trav\u00e9s de los datos de contacto del apartado de INFORMACI\u00d3N GENERAL de este Aviso Legal y Condiciones Generales de Uso.<\/p><h3>VI. ACCIONES LEGALES, LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/h3><p><span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p><p>La relaci\u00f3n entre el Usuario y <span class=\"blanc-space ng-binding\">Literata Beer Garden<\/span> se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los jueces y tribunales que correspondan conforme a derecho.<\/p><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b0206b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0206b7\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5b96940\" data-id=\"5b96940\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-58ed1b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58ed1b6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2fda5c5\" data-id=\"2fda5c5\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b0855f8 elementor-widget elementor-widget-image\" data-id=\"b0855f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"288\" src=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png\" class=\"attachment-full size-full wp-image-106\" alt=\"\" srcset=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png 800w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco-300x108.png 300w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco-768x276.png 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23b3837 elementor-widget elementor-widget-text-editor\" data-id=\"23b3837\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Gourmet brewery and burger bar with imported beers, tapas, and a great atmosphere.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b307104 elementor-widget elementor-widget-heading\" data-id=\"b307104\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Follow us on social media<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d567a08 elementor-shape-square e-grid-align-left e-grid-align-mobile-center elementor-grid-0 elementor-widget elementor-widget-social-icons\" data-id=\"d567a08\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-facebook elementor-repeater-item-02f0f66\" href=\"https:\/\/www.facebook.com\/literata.beergarden.nigran\/?locale=es_ES\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Facebook<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f3843da\" href=\"https:\/\/www.instagram.com\/literatanigran\/?hl=es\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewbox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-22ee3a8\" data-id=\"22ee3a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27c597a elementor-widget elementor-widget-heading\" data-id=\"27c597a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Links<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8543ff0 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"8543ff0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Home<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/nosotros\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">About Us<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/menu\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Menu<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/contacto\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Contact<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-9e8e907\" data-id=\"9e8e907\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0154685 elementor-widget elementor-widget-heading\" data-id=\"0154685\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Legal<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-83d40a2 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"83d40a2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/aviso-legal\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Legal Notice<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/politica-de-privacidad\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Privacy Policy<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/politica-de-cookies\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Cookie Policy<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/literatabeergarden.com\/en\/accesibilidad\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-angle-right\" viewbox=\"0 0 256 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Accessibility<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-cebf0c9\" data-id=\"cebf0c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5eac982 elementor-widget elementor-widget-heading\" data-id=\"5eac982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Contact and Location<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb48b05 elementor-align-start elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"bb48b05\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/maps.app.goo.gl\/KPbJtEsDcRk4JF3U9\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-map-marker-alt\" viewbox=\"0 0 384 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M172.268 501.67C26.97 291.031 0 269.413 0 192 0 85.961 85.961 0 192 0s192 85.961 192 192c0 77.413-26.97 99.031-172.268 309.67-9.535 13.774-29.93 13.773-39.464 0zM192 272c44.183 0 80-35.817 80-80s-35.817-80-80-80-80 35.817-80 80 35.817 80 80 80z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Estrada Po-R, 120, Local 1, 36350 Nigr\u00e1n, Pontevedra<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"tel:+34986116008\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-phone-alt\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M497.39 361.8l-112-48a24 24 0 0 0-28 6.9l-49.6 60.6A370.66 370.66 0 0 1 130.6 204.11l60.6-49.6a23.94 23.94 0 0 0 6.9-28l-48-112A24.16 24.16 0 0 0 122.6.61l-104 24A24 24 0 0 0 0 48c0 256.5 207.9 464 464 464a24 24 0 0 0 23.4-18.6l24-104a24.29 24.29 0 0 0-14.01-27.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">+34 986 11 60 08<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-far-clock\" viewbox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M256 8C119 8 8 119 8 256s111 248 248 248 248-111 248-248S393 8 256 8zm0 448c-110.5 0-200-89.5-200-200S145.5 56 256 56s200 89.5 200 200-89.5 200-200 200zm61.8-104.4l-84.9-61.7c-3.1-2.3-4.9-5.9-4.9-9.7V116c0-6.6 5.4-12 12-12h32c6.6 0 12 5.4 12 12v141.7l66.8 48.6c5.4 3.9 6.5 11.4 2.6 16.8L334.6 349c-3.9 5.3-11.4 6.5-16.8 2.6z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">L-J 18:30-23:30 \u00b7 V 13:00-16:00 \/ 18:30-23:00 \u00b7 S-D 12:30-23:30 \u00b7 Martes cerrado.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-7b7c333 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7b7c333\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-129ffba\" data-id=\"129ffba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ef88290 elementor-widget elementor-widget-text-editor\" data-id=\"ef88290\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Website created with \u2764\ufe0f by <a href=\"https:\/\/www.sofycom.com\/\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #ffffff\">Sofycom<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8278a2f\" data-id=\"8278a2f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d19384 elementor-widget elementor-widget-text-editor\" data-id=\"4d19384\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Copyright \u00a9 2025. All rights reserved.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-5c3fcc1 e-con-full e-flex e-con e-parent\" data-id=\"5c3fcc1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-565e73b elementor-widget elementor-widget-image\" data-id=\"565e73b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"48\" src=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/kd-sofycom-low-1024x62.png\" class=\"attachment-large size-large wp-image-431\" alt=\"\" srcset=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/kd-sofycom-low-1024x62.png 1024w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/kd-sofycom-low-300x18.png 300w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/kd-sofycom-low-768x47.png 768w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/kd-sofycom-low-1536x94.png 1536w, https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/kd-sofycom-low.png 2000w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Inicio Nosotros Men\u00fa Contacto PIDE ONLINE Aviso Legal Inicio Aviso legal AVISO LEGAL Y CONDICIONES GENERALES DE USO https:\/\/www.literatabeergarden.com I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"footnotes":""},"class_list":["post-357","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso Legal - Literata Beer Garden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/literatabeergarden.com\/en\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal - Literata Beer Garden\" \/>\n<meta property=\"og:description\" content=\"Inicio Nosotros Men\u00fa Contacto PIDE ONLINE Aviso Legal Inicio Aviso legal AVISO LEGAL Y CONDICIONES GENERALES DE USO https:\/\/www.literatabeergarden.com I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/literatabeergarden.com\/en\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Literata Beer Garden\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-21T09:49:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"288\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/\",\"name\":\"Aviso Legal - Literata Beer Garden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/literatabeergarden.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-blanco.png\",\"datePublished\":\"2025-09-18T11:11:44+00:00\",\"dateModified\":\"2025-10-21T09:49:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/literatabeergarden.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-blanco.png\",\"contentUrl\":\"https:\\\/\\\/literatabeergarden.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-blanco.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/literatabeergarden.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/#website\",\"url\":\"https:\\\/\\\/literatabeergarden.com\\\/\",\"name\":\"Literata Beer Garden\",\"description\":\"Cervecer\u00eda y hamburgueser\u00eda gourmet con cervezas importadas, tapas y el mejor ambiente.\",\"publisher\":{\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/literatabeergarden.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/#organization\",\"name\":\"Literata Beer Garden\",\"url\":\"https:\\\/\\\/literatabeergarden.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/literatabeergarden.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-literata-full2.jpg\",\"contentUrl\":\"https:\\\/\\\/literatabeergarden.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/logo-literata-full2.jpg\",\"width\":706,\"height\":691,\"caption\":\"Literata Beer Garden\"},\"image\":{\"@id\":\"https:\\\/\\\/literatabeergarden.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal - Literata Beer Garden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/literatabeergarden.com\/en\/aviso-legal\/","og_locale":"en_GB","og_type":"article","og_title":"Aviso Legal - Literata Beer Garden","og_description":"Inicio Nosotros Men\u00fa Contacto PIDE ONLINE Aviso Legal Inicio Aviso legal AVISO LEGAL Y CONDICIONES GENERALES DE USO https:\/\/www.literatabeergarden.com I. INFORMACI\u00d3N GENERAL En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n [&hellip;]","og_url":"https:\/\/literatabeergarden.com\/en\/aviso-legal\/","og_site_name":"Literata Beer Garden","article_modified_time":"2025-10-21T09:49:25+00:00","og_image":[{"width":800,"height":288,"url":"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/literatabeergarden.com\/aviso-legal\/","url":"https:\/\/literatabeergarden.com\/aviso-legal\/","name":"Aviso Legal - Literata Beer Garden","isPartOf":{"@id":"https:\/\/literatabeergarden.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/literatabeergarden.com\/aviso-legal\/#primaryimage"},"image":{"@id":"https:\/\/literatabeergarden.com\/aviso-legal\/#primaryimage"},"thumbnailUrl":"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png","datePublished":"2025-09-18T11:11:44+00:00","dateModified":"2025-10-21T09:49:25+00:00","breadcrumb":{"@id":"https:\/\/literatabeergarden.com\/aviso-legal\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/literatabeergarden.com\/aviso-legal\/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/literatabeergarden.com\/aviso-legal\/#primaryimage","url":"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png","contentUrl":"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-blanco.png"},{"@type":"BreadcrumbList","@id":"https:\/\/literatabeergarden.com\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/literatabeergarden.com\/"},{"@type":"ListItem","position":2,"name":"Aviso Legal"}]},{"@type":"WebSite","@id":"https:\/\/literatabeergarden.com\/#website","url":"https:\/\/literatabeergarden.com\/","name":"Literata Beer Garden","description":"Cervecer\u00eda y hamburgueser\u00eda gourmet con cervezas importadas, tapas y el mejor ambiente.","publisher":{"@id":"https:\/\/literatabeergarden.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/literatabeergarden.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/literatabeergarden.com\/#organization","name":"Literata Beer Garden","url":"https:\/\/literatabeergarden.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/literatabeergarden.com\/#\/schema\/logo\/image\/","url":"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-literata-full2.jpg","contentUrl":"https:\/\/literatabeergarden.com\/wp-content\/uploads\/2025\/09\/logo-literata-full2.jpg","width":706,"height":691,"caption":"Literata Beer Garden"},"image":{"@id":"https:\/\/literatabeergarden.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/pages\/357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/comments?post=357"}],"version-history":[{"count":25,"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/pages\/357\/revisions"}],"predecessor-version":[{"id":576,"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/pages\/357\/revisions\/576"}],"wp:attachment":[{"href":"https:\/\/literatabeergarden.com\/en\/wp-json\/wp\/v2\/media?parent=357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}